{"id":1178,"date":"2024-02-12T07:55:40","date_gmt":"2024-02-12T07:55:40","guid":{"rendered":"https:\/\/www.lingotop.com\/?p=1178"},"modified":"2024-03-08T06:28:18","modified_gmt":"2024-03-08T06:28:18","slug":"verbos-modales","status":"publish","type":"post","link":"https:\/\/www.lingotop.com\/es\/modal-verbs","title":{"rendered":"Verbos modales"},"content":{"rendered":"<div id=\"lingo-1614555066\" class=\"lingo-before-content-2 lingo-entity-placement\"><div class=\"not\" data-no-auto-translation=\"\">\r\n<div style=\"text-align: center; margin-bottom: 30px; padding: 15px 10px 20px 10px; border: solid #efefef;\">\r\n<div style=\"font-weight: bold; font-size: 120%; padding-bottom: 10px;\">\u00bfQuieres aprender un idioma m\u00e1s r\u00e1pido?<\/div>\r\n<p>La aplicaci\u00f3n adecuada puede marcar la diferencia.<\/p>\r\n<p>Haz este quiz gratuito de 30 segundos y encuentra la app que te ayuda a aprender m\u00e1s r\u00e1pido.<\/p>\r\n<a class=\"a4\" href=\"https:\/\/www.lingotop.com\/es\/prueba-de-lengua\" rel=\"nofollow noopener\" target=\"_blank\">Empezar el quiz<\/a><br \/>\r\n<\/div>\t<\/div><\/div><p>Los verbos modales son un aspecto fundamental del lenguaje, presente en varias lenguas de todo el mundo. Desempe\u00f1an un papel crucial a la hora de transmitir distintos matices de significado y expresar grados de posibilidad, necesidad, permiso y obligaci\u00f3n. En este art\u00edculo estudiaremos el concepto de verbo modal y su importancia en la comunicaci\u00f3n ling\u00fc\u00edstica.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u00bfQu\u00e9 son los verbos modales?<\/h2>\n<p>Los verbos modales, tambi\u00e9n conocidos como auxiliares modales o modales, son una categor\u00eda de verbos auxiliares que modifican al verbo principal de una frase para transmitir distintos matices de significado. A diferencia de los verbos regulares, los modales no cambian de forma seg\u00fan el sujeto. Van seguidos de la forma base del verbo principal y se utilizan para expresar una amplia gama de ideas, entre ellas:<\/p>\n<ol>\n<li>\n<p>Posibilidad: Los verbos modales como \"can\", \"could\", \"may\" y \"might\" se utilizan para indicar la posibilidad o probabilidad de que ocurra un acontecimiento. Por ejemplo: \"Puede hablar espa\u00f1ol con fluidez\".<\/p>\n<\/li>\n<li>\n<p>Necesidad: Los verbos modales como \"must\" y \"have to\" se emplean para expresar obligaciones o requisitos. Por ejemplo: \"Debes terminar tus deberes\".<\/p>\n<\/li>\n<li>\n<p>Permiso: Los verbos modales como \"may\", \"can\" y \"could\" se utilizan para pedir o conceder permiso. Por ejemplo: \"\u00bfPuedo usar tu bol\u00edgrafo?\".<\/p>\n<\/li>\n<li>\n<p>Capacidad: Modales como \"can\", \"could\" y \"be able to\" se emplean para denotar la capacidad o habilidad de una persona para hacer algo. Por ejemplo: \"Puede nadar\".<\/p>\n<\/li>\n<li>\n<p>Consejos y sugerencias: Los verbos modales como \"should\" y \"ought to\" se utilizan para dar consejos o hacer sugerencias. Por ejemplo: \"Deber\u00edas estudiar para el examen\".<\/p>\n<\/li>\n<li>\n<p>Probabilidad: Los verbos modales como \"debe\", \"deber\u00eda\" y \"podr\u00eda\" tambi\u00e9n pueden transmitir grados de certeza o probabilidad. Por ejemplo: \"Debe estar lloviendo si han cancelado el picnic\".<\/p>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2>La importancia de los verbos modales<\/h2>\n<p>Los verbos modales son indispensables para transmitir el significado con precisi\u00f3n y eficacia. Permiten a hablantes y escritores expresar matices que de otro modo ser\u00eda dif\u00edcil articular. Los verbos modales nos permiten comunicarnos:<\/p>\n<ol>\n<li>\n<p>Grados de certeza: Los verbos modales nos ayudan a expresar el grado de confianza que tenemos en una afirmaci\u00f3n. Por ejemplo, \"Debe estar en casa\" sugiere un mayor nivel de certeza que \"Podr\u00eda estar en casa\".<\/p>\n<\/li>\n<li>\n<p>Educaci\u00f3n y cortes\u00eda: Los verbos modales pueden utilizarse para hacer peticiones u ofertas de forma m\u00e1s educada y cort\u00e9s. Por ejemplo, \"\u00bfPodr\u00eda pasarme la sal?\" es m\u00e1s cort\u00e9s que \"P\u00e1same la sal\".<\/p>\n<\/li>\n<li>\n<p>Obligaciones y deberes: Los verbos modales aclaran si una acci\u00f3n es obligatoria u opcional. Esto es especialmente importante en contextos legales, \u00e9ticos y sociales.<\/p>\n<\/li>\n<li>\n<p>Expresar situaciones hipot\u00e9ticas: Los verbos modales nos permiten hablar de situaciones hipot\u00e9ticas y sus posibles resultados. Por ejemplo: \"Si fuera rico, podr\u00eda viajar por el mundo\".<\/p>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2>Lista de ejemplos de verbos modales<\/h2>\n<p>Aqu\u00ed tienes una lista de verbos modales comunes con ejemplos:<\/p>\n<p>&nbsp;<\/p>\n<p>Can:<\/p>\n<ul class=\"toppad\">\n<li>S\u00e9 nadar.<\/li>\n<li>\u00bfPuede ayudarme con esto?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Podr\u00eda:<\/p>\n<ul class=\"toppad\">\n<li>Sab\u00eda tocar el piano cuando era m\u00e1s joven.<\/li>\n<li>\u00bfMe pasas la sal, por favor?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Mayo:<\/p>\n<ul class=\"toppad\">\n<li>\u00bfPuedo pasar?<\/li>\n<li>Puede que llueva m\u00e1s tarde, as\u00ed que ll\u00e9vate un paraguas.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Muy bien:<\/p>\n<ul class=\"toppad\">\n<li>Puede que nos acompa\u00f1e a cenar.<\/li>\n<li>Puede que visite el museo ma\u00f1ana.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Debe:<\/p>\n<ul class=\"toppad\">\n<li>Debe entregar su tarea antes del viernes.<\/li>\n<li>Se hace tarde; debo irme ya.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Qu\u00e9date:<\/p>\n<ul class=\"toppad\">\n<li>\u00bfVamos a dar un paseo?<\/li>\n<li>Informar\u00e9 al director sobre el asunto.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Deber\u00eda:<\/p>\n<ul class=\"toppad\">\n<li>Debes comer m\u00e1s verduras para llevar una dieta equilibrada.<\/li>\n<li>Deber\u00eda estudiar para el pr\u00f3ximo examen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Will:<\/p>\n<ul class=\"toppad\">\n<li>Te llamar\u00e9 m\u00e1s tarde.<\/li>\n<li>\u00bfAsistir\u00e1n a la fiesta?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Lo har\u00eda:<\/p>\n<ul class=\"toppad\">\n<li>\u00bfQuieres un t\u00e9?<\/li>\n<li>Si yo fuera t\u00fa, aceptar\u00eda la oferta de trabajo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Deber\u00eda:<\/p>\n<ul class=\"toppad\">\n<li>Deber\u00edas disculparte por tu comportamiento.<\/li>\n<li>Deber\u00edan llegar pronto.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Es necesario:<\/p>\n<ul class=\"toppad\">\n<li>Tengo que terminar este informe hoy.<\/li>\n<li>\u00bfEs necesario que asistan a la reuni\u00f3n?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Tengo que hacerlo:<\/p>\n<ul class=\"toppad\">\n<li>Ma\u00f1ana tiene que asistir a la conferencia.<\/li>\n<li>Tenemos que pagar las facturas a final de mes.<\/li>\n<\/ul>\n<p>Estos ejemplos demuestran la versatilidad de los verbos modales para expresar distintos significados y funciones en las frases. Los verbos modales son esenciales para transmitir matices como posibilidad, necesidad, permiso, obligaci\u00f3n, etc. en varios idiomas.<\/p>\n<p>&nbsp;<\/p>\n<h2>Art\u00edculos relacionados<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.lingotop.com\/es\/verbos-modales-en-ingles\/\">Verbos modales en ingl\u00e9s<\/a><\/li>\n<li><a href=\"https:\/\/www.lingotop.com\/es\/verbos-modales-en-frances\/\">Verbos modales en franc\u00e9s<\/a><\/li>\n<li><a href=\"https:\/\/www.lingotop.com\/es\/verbos-modales-en-aleman\/\">Verbos modales en alem\u00e1n<\/a><\/li>\n<\/ul>\n<div id=\"lingo-1212120626\" class=\"lingo-after-content-2 lingo-entity-placement\"><div class=\"not\" data-no-auto-translation=\"\">\r\n<div style=\"text-align: center; margin-bottom: 30px; padding: 15px 10px 20px 10px; border: solid #efefef;\">\r\n<div style=\"font-weight: bold; font-size: 120%; padding-bottom: 10px;\">\u00bfQuieres aprender un idioma m\u00e1s r\u00e1pido?<\/div>\r\n<p>La aplicaci\u00f3n adecuada puede marcar la diferencia.<\/p>\r\n<p>Haz este quiz gratuito de 30 segundos y encuentra la app que te ayuda a aprender m\u00e1s r\u00e1pido.<\/p>\r\n<a class=\"a4\" href=\"https:\/\/www.lingotop.com\/es\/prueba-de-lengua\" rel=\"nofollow noopener\" target=\"_blank\">Empezar el quiz<\/a><br \/>\r\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Los verbos modales son un aspecto fundamental del lenguaje, presente en varias lenguas de todo el mundo. Desempe\u00f1an un papel crucial a la hora de transmitir distintos matices de significado y expresar grados de posibilidad, necesidad, permiso y obligaci\u00f3n. En este art\u00edculo estudiaremos el concepto de verbo modal y su importancia en la comunicaci\u00f3n ling\u00fc\u00edstica.   ... <a title=\"Verbos modales\" class=\"read-more\" href=\"https:\/\/www.lingotop.com\/es\/modal-verbs\" aria-label=\"Leer m\u00e1s sobre Modal Verbs\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,27],"tags":[],"class_list":["post-1178","post","type-post","status-publish","format-standard","hentry","category-main-article","category-universal-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modal Verbs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lingotop.com\/es\/verbos-modales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modal Verbs\" \/>\n<meta property=\"og:description\" content=\"Modal verbs are a fundamental aspect of language, found in various languages across the world. They play a crucial role in conveying different nuances of meaning and expressing degrees of possibility, necessity, permission, and obligation. In this article, we will look into the concept of modal verbs and explore their significance in language communication. &nbsp; ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lingotop.com\/es\/verbos-modales\/\" \/>\n<meta property=\"og:site_name\" content=\"Lingotop\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-12T07:55:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T06:28:18+00:00\" \/>\n<meta name=\"author\" content=\"Jesper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jesper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs\"},\"author\":{\"name\":\"Jesper\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#\\\/schema\\\/person\\\/dedffff5c4a0c0a1bfc85f35b9e57021\"},\"headline\":\"Modal Verbs\",\"datePublished\":\"2024-02-12T07:55:40+00:00\",\"dateModified\":\"2024-03-08T06:28:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs\"},\"wordCount\":689,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#organization\"},\"articleSection\":[\"Main article\",\"Universal article\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs\",\"url\":\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs\",\"name\":\"Modal Verbs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#website\"},\"datePublished\":\"2024-02-12T07:55:40+00:00\",\"dateModified\":\"2024-03-08T06:28:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/modal-verbs#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lingotop.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modal Verbs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/\",\"name\":\"Lingotop\",\"description\":\"Learn languages online\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#organization\",\"name\":\"Lingotop\",\"url\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lingotop.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/lingotop-logo-new.png?wsr\",\"contentUrl\":\"https:\\\/\\\/www.lingotop.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/lingotop-logo-new.png?wsr\",\"width\":989,\"height\":222,\"caption\":\"Lingotop\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lingotop.com\\\/en\\\/#\\\/schema\\\/person\\\/dedffff5c4a0c0a1bfc85f35b9e57021\",\"name\":\"Jesper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"caption\":\"Jesper\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verbos modales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lingotop.com\/es\/verbos-modales\/","og_locale":"es_ES","og_type":"article","og_title":"Modal Verbs","og_description":"Modal verbs are a fundamental aspect of language, found in various languages across the world. They play a crucial role in conveying different nuances of meaning and expressing degrees of possibility, necessity, permission, and obligation. In this article, we will look into the concept of modal verbs and explore their significance in language communication. &nbsp; ... Leer m\u00e1s","og_url":"https:\/\/www.lingotop.com\/es\/verbos-modales\/","og_site_name":"Lingotop","article_published_time":"2024-02-12T07:55:40+00:00","article_modified_time":"2024-03-08T06:28:18+00:00","author":"Jesper","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jesper","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lingotop.com\/modal-verbs#article","isPartOf":{"@id":"https:\/\/www.lingotop.com\/modal-verbs"},"author":{"name":"Jesper","@id":"https:\/\/www.lingotop.com\/en\/#\/schema\/person\/dedffff5c4a0c0a1bfc85f35b9e57021"},"headline":"Modal Verbs","datePublished":"2024-02-12T07:55:40+00:00","dateModified":"2024-03-08T06:28:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lingotop.com\/modal-verbs"},"wordCount":689,"publisher":{"@id":"https:\/\/www.lingotop.com\/en\/#organization"},"articleSection":["Main article","Universal article"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.lingotop.com\/modal-verbs","url":"https:\/\/www.lingotop.com\/modal-verbs","name":"Verbos modales","isPartOf":{"@id":"https:\/\/www.lingotop.com\/en\/#website"},"datePublished":"2024-02-12T07:55:40+00:00","dateModified":"2024-03-08T06:28:18+00:00","breadcrumb":{"@id":"https:\/\/www.lingotop.com\/modal-verbs#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lingotop.com\/modal-verbs"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lingotop.com\/modal-verbs#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lingotop.com\/"},{"@type":"ListItem","position":2,"name":"Modal Verbs"}]},{"@type":"WebSite","@id":"https:\/\/www.lingotop.com\/en\/#website","url":"https:\/\/www.lingotop.com\/en\/","name":"Lingotop","description":"Aprender idiomas en l\u00ednea","publisher":{"@id":"https:\/\/www.lingotop.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lingotop.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.lingotop.com\/en\/#organization","name":"Lingotop","url":"https:\/\/www.lingotop.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lingotop.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.lingotop.com\/wp-content\/uploads\/2024\/03\/lingotop-logo-new.png?wsr","contentUrl":"https:\/\/www.lingotop.com\/wp-content\/uploads\/2024\/03\/lingotop-logo-new.png?wsr","width":989,"height":222,"caption":"Lingotop"},"image":{"@id":"https:\/\/www.lingotop.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.lingotop.com\/en\/#\/schema\/person\/dedffff5c4a0c0a1bfc85f35b9e57021","name":"Jesper","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","caption":"Jesper"}}]}},"_links":{"self":[{"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/posts\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/comments?post=1178"}],"version-history":[{"count":6,"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/posts\/1178\/revisions"}],"predecessor-version":[{"id":1861,"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/posts\/1178\/revisions\/1861"}],"wp:attachment":[{"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/categories?post=1178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lingotop.com\/es\/wp-json\/wp\/v2\/tags?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}